{"id":4937,"date":"2016-11-02T09:48:21","date_gmt":"2016-11-02T08:48:21","guid":{"rendered":"http:\/\/powell365-web2562.cloudapp.net\/?p=4937"},"modified":"2024-01-19T12:32:20","modified_gmt":"2024-01-19T11:32:20","slug":"meilleur-pratiques-intranet-gouvernance","status":"publish","type":"post","link":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/","title":{"rendered":"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet"},"content":{"rendered":"<h2 style=\"text-align: center;\">La gouvernance d\u2019un intranet<\/h2>\n<p style=\"text-align: justify;\">La gouvernance d\u2019un intranet fait partie des \u00e9tapes les plus importantes dans la cr\u00e9ation d\u2019un intranet. \u00a0La structure et la politique de l\u2019entreprise pourront avoir un impact sur l\u2019utilisation du portail intranet par les employ\u00e9s. La solution Powell 365 a \u00e9t\u00e9 con\u00e7ue pour que chacun tire au mieux parti de sa plateforme collaborative de travail. Afin d&#8217;aider les personnes en charge du projet nous vous donnons quelques bonnes pratiques de gouvernance \u00e0 mettre en place.<\/p>\n<h3 style=\"text-align: justify;\">D\u00e9finition de la gouvernance<\/h3>\n<p style=\"text-align: justify;\">Selon <u>UN ESCAP<\/u> le mot gouvernance se d\u00e9finit comme \u00ab le processus de prise de d\u00e9cision et le processus par lequel les d\u00e9cisions sont mises en \u0153uvre.&#8221; Par cons\u00e9quent, vous pouvez d\u00e9finir la gouvernance d\u2019un portail intranet comme l&#8217;ensemble des processus qui guident la gestion et le d\u00e9veloppement d&#8217;un intranet. Lorsqu&#8217;il est correctement con\u00e7u, un intranet collaboratif \u00e9volue automatiquement. Cependant, vous ne pouvez pas attendre d\u2019une plateforme collaborative de travail qu\u2019elle fonctionne sans qu\u2019elle soit g\u00e9r\u00e9e correctement.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">1: R\u00f4les et Responsabilit\u00e9s<\/h3>\n<p style=\"text-align: justify;\">La premi\u00e8re \u00e9tape est de d\u00e9terminer les r\u00f4les et les responsabilit\u00e9s de chacun. Il est quasiment impossible de d\u00e9finir une seule et unique personne en charge du portail puisque chaque d\u00e9partement est concern\u00e9. L\u2019\u00e9quipe choisie doit \u00eatre constitu\u00e9e d\u2019experts charg\u00e9s du d\u00e9veloppement de l\u2019intranet. Les membres de l\u2019\u00e9quipe doivent avoir une bonne connaissance des outils. Les \u00e9quipes sont g\u00e9n\u00e9ralement constitu\u00e9es d\u2019un administrateur, de chefs de projet, de personnes charg\u00e9es de r\u00e9diger le contenu et d\u2019un dirigeant d&#8217;entreprise motiv\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">2: D\u00e9finir la strat\u00e9gie<\/h3>\n<p style=\"text-align: justify;\">Dans un second temps il faut d\u00e9terminer la strat\u00e9gie de votre projet intranet. Cela implique de d\u00e9finir une vision strat\u00e9gique et un plan fonctionnel de r\u00e9alisation du portail intranet. Cette \u00e9tape sert \u00e0 \u00e9tablir quel type de contenu sera cr\u00e9\u00e9 et o\u00f9 il sera post\u00e9. Cela permet \u00e9galement de savoir quand les contenus seront publi\u00e9s, \u00e0 quelle fr\u00e9quence, qui les r\u00e9digent, les revoient ou les met \u00e0 jour. Mettre en place une strat\u00e9gie peut \u00eatre intimidante mais c\u2019est une \u00e9tape essentielle pour la gestion de votre intranet. Vos \u00e9quipes travailleront plus efficacement, elles sauront \u00e0 qui s\u2019adresser sans perdre de temps ce qui vous permettra d\u2019avoir un contenu pertinent et un intranet toujours \u00e0 jour.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">3: Cr\u00e9ation de contenu<\/h3>\n<p style=\"text-align: justify;\">C\u2019est gr\u00e2ce au contenu pr\u00e9sent sur votre intranet collaboratif que vos employ\u00e9s pourront avoir acc\u00e8s aux informations et aux derni\u00e8res actualit\u00e9s. De plus, le contenu doit \u00eatre \u00e0 l\u2019image de votre entreprise et de vos valeurs. Assurez-vous de bien d\u00e9finir les personnes en charge de la cr\u00e9ation de contenus. Chaque type de contenu est source d\u2019information \u2013 vid\u00e9o, articles, images\u2026 &#8211; ne le n\u00e9gligez pas. Posez-vous la question de ce qu\u2019attendent vos employ\u00e9s. Un contenu facile \u00e0 lire est un des principaux avantages d\u2019un portail intranet.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">4: Pensez Communication &amp; Collaboration<\/h3>\n<p style=\"text-align: justify;\">Un intranet est pertinent si sa communaut\u00e9 d\u2019utilisateurs est active et engag\u00e9e. Avoir un mod\u00e8le de gouvernance clairement d\u00e9fini ne devrait pas limiter les employ\u00e9s. Les utilisateurs doivent pouvoir donner leur avis et interagir avec ce qu\u2019il se passe sur la plateforme collaborative de travail. Assurez-vous de mettre en place des fonctionnalit\u00e9s interactives lorsque vous construisez vos templates (likes, commentaires\u2026). Le fait d\u2019encourager la communication et la collaboration au sein du portail intranet apporte un plus haut niveau d\u2019engagement du collaborateur et entra\u00eene donc une plus forte utilisation de l\u2019outil.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>Conclusion<\/strong><\/p>\n<p style=\"text-align: justify;\">Lorsque que vous cr\u00e9ez votre intranet collaboratif il est important de penser aux avantages \u00e0 long terme. Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de la plateforme collaborative de travail. Si vous suivez nos conseils, la cr\u00e9ation du portail intranet sera plus facile et vos employ\u00e9s en b\u00e9n\u00e9ficieront.<\/p>\n<p><span id=\"hs-cta-wrapper-392d760a-1053-4bbf-a7f3-01c5484c3ee6\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-392d760a-1053-4bbf-a7f3-01c5484c3ee6\" class=\"hs-cta-node hs-cta-392d760a-1053-4bbf-a7f3-01c5484c3ee6\"><a href=\"https:\/\/hubspot-cta-redirect-eu1-prod.s3.amazonaws.com\/cta\/redirect\/26290363\/392d760a-1053-4bbf-a7f3-01c5484c3ee6\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" id=\"hs-cta-img-392d760a-1053-4bbf-a7f3-01c5484c3ee6\" class=\"hs-cta-img aligncenter\" style=\"border-width: 0px;\" src=\"https:\/\/hubspot-no-cache-eu1-prod.s3.amazonaws.com\/cta\/default\/26290363\/392d760a-1053-4bbf-a7f3-01c5484c3ee6.png\" alt=\"FR - Demo : Powell Intranet\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js-eu1.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(26290363, '392d760a-1053-4bbf-a7f3-01c5484c3ee6', {\"useNewLoader\":\"true\",\"region\":\"eu1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque que vous cr\u00e9ez votre intranet collaborative il est important de penser aux avantages \u00e0 long terme. Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de la plateforme collaborative de travail. <\/p>\n","protected":false},"author":17,"featured_media":4974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1671],"audiences":[],"interests":[],"products":[],"zones":[],"class_list":["post-4937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet<\/title>\n<meta name=\"description\" content=\"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet\" \/>\n<meta property=\"og:description\" content=\"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/\" \/>\n<meta property=\"og:site_name\" content=\"Powell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PowellSoftware\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T08:48:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T11:32:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Esther Daga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:site\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esther Daga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/\"},\"author\":{\"name\":\"Esther Daga\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/3c02dfad8dbb8c86e9d05984104f8f4d\"},\"headline\":\"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet\",\"datePublished\":\"2016-11-02T08:48:21+00:00\",\"dateModified\":\"2024-01-19T11:32:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/\"},\"wordCount\":699,\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/IntranertGovernance-FR_1350x450.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/\",\"name\":\"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/IntranertGovernance-FR_1350x450.png\",\"datePublished\":\"2016-11-02T08:48:21+00:00\",\"dateModified\":\"2024-01-19T11:32:20+00:00\",\"description\":\"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/IntranertGovernance-FR_1350x450.png\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/IntranertGovernance-FR_1350x450.png\",\"width\":1350,\"height\":450,\"caption\":\"meilleur pratiques intranet gouvernance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/meilleur-pratiques-intranet-gouvernance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/.\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conseils pour d\u00e9velopper et g\u00e9rer&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"name\":\"Powell\",\"description\":\"Intelligent Digital Workplace Suite\",\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\",\"name\":\"Powell\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"width\":969,\"height\":969,\"caption\":\"Powell\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PowellSoftware\",\"https:\\\/\\\/x.com\\\/powellsoftware\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBX2pfEUCxJQWCKOx9hvv8w\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/powell-software\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/3c02dfad8dbb8c86e9d05984104f8f4d\",\"name\":\"Esther Daga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g\",\"caption\":\"Esther Daga\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/estherdaga\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet","description":"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/","og_locale":"fr_FR","og_type":"article","og_title":"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet","og_description":"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social","og_url":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/","og_site_name":"Powell","article_publisher":"https:\/\/www.facebook.com\/PowellSoftware","article_published_time":"2016-11-02T08:48:21+00:00","article_modified_time":"2024-01-19T11:32:20+00:00","og_image":[{"width":1350,"height":450,"url":"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png","type":"image\/png"}],"author":"Esther Daga","twitter_card":"summary_large_image","twitter_creator":"@powellsoftware","twitter_site":"@powellsoftware","twitter_misc":{"Written by":"Esther Daga","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#article","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/"},"author":{"name":"Esther Daga","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/3c02dfad8dbb8c86e9d05984104f8f4d"},"headline":"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet","datePublished":"2016-11-02T08:48:21+00:00","dateModified":"2024-01-19T11:32:20+00:00","mainEntityOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/"},"wordCount":699,"publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/","url":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/","name":"Conseils pour d\u00e9velopper et g\u00e9rer votre portail intranet","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#primaryimage"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png","datePublished":"2016-11-02T08:48:21+00:00","dateModified":"2024-01-19T11:32:20+00:00","description":"Mettre en place une gouvernance bien pens\u00e9e et solide vous aidera dans l\u2019impl\u00e9mentation de votre intranet collaboratif et social","breadcrumb":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#primaryimage","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2016\/10\/IntranertGovernance-FR_1350x450.png","width":1350,"height":450,"caption":"meilleur pratiques intranet gouvernance"},{"@type":"BreadcrumbList","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/meilleur-pratiques-intranet-gouvernance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powell-software.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/powell-software.com\/fr\/resources\/.\/blog\/"},{"@type":"ListItem","position":3,"name":"Conseils pour d\u00e9velopper et g\u00e9rer&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/powell-software.com\/fr\/#website","url":"https:\/\/powell-software.com\/fr\/","name":"Powell","description":"Intelligent Digital Workplace Suite","publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powell-software.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/powell-software.com\/fr\/#organization","name":"Powell","url":"https:\/\/powell-software.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","width":969,"height":969,"caption":"Powell"},"image":{"@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PowellSoftware","https:\/\/x.com\/powellsoftware","https:\/\/www.youtube.com\/channel\/UCBX2pfEUCxJQWCKOx9hvv8w","https:\/\/fr.linkedin.com\/company\/powell-software"]},{"@type":"Person","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/3c02dfad8dbb8c86e9d05984104f8f4d","name":"Esther Daga","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc28e729765cd0b765addf4944baf188854461984219de670e2f2ac611627c86?s=96&d=mm&r=g","caption":"Esther Daga"},"sameAs":["https:\/\/www.linkedin.com\/in\/estherdaga\/"]}]}},"_links":{"self":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/4937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/comments?post=4937"}],"version-history":[{"count":0,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/4937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media\/4974"}],"wp:attachment":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media?parent=4937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/categories?post=4937"},{"taxonomy":"audiences","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/audiences?post=4937"},{"taxonomy":"interests","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/interests?post=4937"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/products?post=4937"},{"taxonomy":"zones","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/zones?post=4937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}