{"id":45982,"date":"2021-06-06T11:03:50","date_gmt":"2021-06-06T10:03:50","guid":{"rendered":"https:\/\/powell-software.com\/?p=45982"},"modified":"2023-10-30T15:30:40","modified_gmt":"2023-10-30T14:30:40","slug":"microsoft-viva-connections","status":"publish","type":"post","link":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/","title":{"rendered":"Offrez l&#8217;exp\u00e9rience Microsoft Viva Connections en quelques clics"},"content":{"rendered":"<p style=\"text-align: justify;\">Le lancement de Microsoft Viva a fait grand bruit et les gens se sont demand\u00e9s de quoi il s&#8217;agissait, quand ses diff\u00e9rentes fonctionnalit\u00e9s seraient disponibles et, surtout, comment il fonctionnerait avec la Digital Workplace de Powell Software. Apr\u00e8s avoir \u00e9t\u00e9 annonc\u00e9 pour la premi\u00e8re fois en avril 2021, nous sommes ravis de voir la premi\u00e8re des quatre fonctions, Viva Connections, maintenant disponible.<\/p>\n<p style=\"text-align: justify;\">Chez Powell Software, notre objectif est d&#8217;<a href=\"https:\/\/powell-software.com\/fr\/audience-hr-fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">am\u00e9liorer l&#8217;engagement des employ\u00e9s<\/a>, <a href=\"https:\/\/powell-software.com\/fr\/audience-communications-fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">la communication d&#8217;entreprise<\/a> et de<a href=\"https:\/\/powell-software.com\/en\/solution-teams-goverance\/\" target=\"_blank\" rel=\"noopener noreferrer\"> simplifier la collaboration<\/a>. Nous aidons les entreprises \u00e0 cr\u00e9er la meilleure exp\u00e9rience pour leurs employ\u00e9s gr\u00e2ce \u00e0 des solutions de Digital Workplace adapt\u00e9es au nouvel environnement de<a href=\"https:\/\/powell-software.com\/fr\/solution-hybrid-workplace-fr\/\" target=\"_blank\" rel=\"noopener noreferrer\"> travail hybride<\/a> et flexible. Pour ce faire, nous connectons les employ\u00e9s et les organisations plus efficacement gr\u00e2ce \u00e0 une Digital Workplace unique qui relie l&#8217;intranet \u00e0 Teams.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/powell-software.com\/en\/digital-workplace-solution\/\"><img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-67230 aligncenter\" src=\"https:\/\/live-powell-software.pantheonsite.io\/wp-content\/uploads\/2021\/06\/Slide7.jpg\" alt=\"Powell Software Digital Workplace\" width=\"743\" height=\"418\" srcset=\"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7.jpg 1280w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-480x270.jpg 480w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-1200x675.jpg 1200w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-768x432.jpg 768w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-57x32.jpg 57w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-200x113.jpg 200w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-400x225.jpg 400w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-600x338.jpg 600w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide7-800x450.jpg 800w\" sizes=\"auto, (max-width: 743px) 100vw, 743px\" \/><\/a><\/p>\n<h2 style=\"text-align: justify;\"><\/h2>\n<h2 style=\"text-align: center;\">Qu&#8217;est-ce que Viva Connections ?<\/h2>\n<p style=\"text-align: justify;\">Viva Connections est l&#8217;un des quatre modules de Viva. Il constitue une passerelle entre les sites SharePoint et Microsoft Teams. Viva Connections permet aux utilisateurs de d\u00e9couvrir et de rechercher du contenu, des sites et des nouvelles directement \u00e0 partir du menu principal de Microsoft Teams pour permettre :<\/p>\n<ol style=\"text-align: justify;\">\n<li>Lier SharePoint \u00e0 Teams<\/li>\n<li>La mise en \u00e9vidence de ressources sp\u00e9cifiques<\/li>\n<li>Trouver des informations sur l&#8217;entreprise directement \u00e0 partir de Teams<\/li>\n<li>Rechercher du contenu dans SharePoint \u00e0 partir de Teams<br \/>\n<img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-67235 \" src=\"https:\/\/live-powell-software.pantheonsite.io\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience.png\" alt=\"Viva Connections Experience\" width=\"766\" height=\"660\" srcset=\"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience.png 903w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-480x414.png 480w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-768x662.png 768w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-37x32.png 37w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-200x172.png 200w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-400x345.png 400w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-600x517.png 600w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections-Experience-800x689.png 800w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/li>\n<\/ol>\n<h3><\/h3>\n<h2 style=\"text-align: center;\">Quand Viva Connections sera-t-il disponible ?<\/h2>\n<p style=\"text-align: justify;\">\u00c0 l&#8217;occasion du lancement de Microsoft Viva, nous avons explor\u00e9 <a href=\"https:\/\/powell-software.com\/fr\/powell-365-microsoft-viva\/\" target=\"_blank\" rel=\"noopener noreferrer\">comment Powell Software s&#8217;appuiera sur Viva<\/a> pour offrir aux employ\u00e9s une exp\u00e9rience toujours \u00e0 jour et compl\u00e8te. Nous avons \u00e9t\u00e9 enthousiasm\u00e9s par l&#8217;exploration de Viva et de ses capacit\u00e9s, car elle repr\u00e9sente une opportunit\u00e9 pour Powell Software de renforcer davantage la connexion entre l&#8217;intranet et Teams.<\/p>\n<p style=\"text-align: justify;\">C&#8217;est pourquoi nous sommes maintenant mobilis\u00e9s pour tirer parti des opportunit\u00e9s offertes par Microsoft Viva le plus rapidement possible. Viva Connections est disponible d\u00e8s maintenant et les clients de Powell Software peuvent d\u00e9j\u00e0 le mettre en \u0153uvre.<\/p>\n<h3><\/h3>\n<h2 style=\"text-align: center;\">Comment activer Viva Connections ?<\/h2>\n<p style=\"text-align: justify;\">Microsoft a r\u00e9cemment publi\u00e9 la possibilit\u00e9 de commencer \u00e0 d\u00e9ployer Microsoft Viva Connections. Le processus doit \u00eatre effectu\u00e9 par un administrateur qui provisionnera cette premi\u00e8re version via PowerShell et la t\u00e9l\u00e9chargera en tant qu&#8217;application vers Microsoft Teams.<\/p>\n<h3><\/h3>\n<h2 style=\"text-align: center;\">Comment d\u00e9ployer vos propres boutons Powell Intranet dans Teams en quelques clics ?<\/h2>\n<p style=\"text-align: justify;\">Chez Powell Software, nous offrons \u00e0 nos clients non seulement la compatibilit\u00e9 avec Viva Connections, mais aussi la possibilit\u00e9 de g\u00e9n\u00e9rer cette exp\u00e9rience tr\u00e8s facilement. Les administrateurs peuvent cr\u00e9er des modules d\u00e9ployables en tant que boutons dans Teams en quelques clics et autant de fois qu&#8217;ils le souhaitent.<\/p>\n<p style=\"text-align: justify;\"><img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-67240 \" src=\"https:\/\/live-powell-software.pantheonsite.io\/wp-content\/uploads\/2021\/06\/Slide3.jpg\" alt=\"Powell software viva connections\" width=\"1097\" height=\"617\" srcset=\"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3.jpg 1280w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-480x270.jpg 480w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-1200x675.jpg 1200w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-768x432.jpg 768w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-57x32.jpg 57w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-200x113.jpg 200w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-400x225.jpg 400w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-600x338.jpg 600w, https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Slide3-800x450.jpg 800w\" sizes=\"auto, (max-width: 1097px) 100vw, 1097px\" \/><\/p>\n<p style=\"text-align: justify;\">La valeur ajout\u00e9e de <a href=\"https:\/\/powell-software.com\/fr\/fonctionnalites-portail-office-365\/\" target=\"_blank\" rel=\"noopener noreferrer\">Powell Intranet<\/a> ne se limite bien s\u00fbr pas \u00e0 cette fonctionnalit\u00e9 tr\u00e8s pratique au quotidien. Notre solution de Digital Workplace vous permet \u00e9galement d&#8217;engager vos employ\u00e9s et de couvrir tous les sc\u00e9narios de l&#8217;environnement de travail hybride, que ce soit dans l&#8217;intranet de l&#8217;entreprise ou dans Teams.<\/p>\n<p style=\"text-align: justify;\">Vous souhaitez en savoir plus sur les solutions de Powell Software pour am\u00e9liorer l&#8217;<a href=\"https:\/\/powell-software.com\/fr\/audience-hr-fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">exp\u00e9rience de vos employ\u00e9s<\/a> ? Parlez d\u00e8s aujourd&#8217;hui \u00e0 notre \u00e9quipe de votre projet et nous vous aiderons \u00e0 trouver une solution adapt\u00e9e \u00e0 vos besoins.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a class=\"btn btn-primary\" href=\"\/fr\/demo\/\">OBTENIR UNE D\u00c9MONSTRATION<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Avec Powell Software, nous vous facilitons la t\u00e2che. <\/p>\n","protected":false},"author":32,"featured_media":67245,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1671],"audiences":[1688],"interests":[1676],"products":[],"zones":[],"class_list":["post-45982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","audiences-information-technologie","interests-digital-workplace"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Offrez l&#039;exp\u00e9rience Microsoft Viva Connections en quelques clics<\/title>\n<meta name=\"description\" content=\"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offrez l&#039;exp\u00e9rience Microsoft Viva Connections en quelques clics\" \/>\n<meta property=\"og:description\" content=\"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/\" \/>\n<meta property=\"og:site_name\" content=\"Powell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PowellSoftware\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-06T10:03:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T14:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yvonne Harris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:site\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvonne Harris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/\"},\"author\":{\"name\":\"Yvonne Harris\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/d82fc37718810125131568da05cb0549\"},\"headline\":\"Offrez l&#8217;exp\u00e9rience Microsoft Viva Connections en quelques clics\",\"datePublished\":\"2021-06-06T10:03:50+00:00\",\"dateModified\":\"2023-10-30T14:30:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/\"},\"wordCount\":570,\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Viva-Connections.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/\",\"name\":\"Offrez l'exp\u00e9rience Microsoft Viva Connections en quelques clics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Viva-Connections.png\",\"datePublished\":\"2021-06-06T10:03:50+00:00\",\"dateModified\":\"2023-10-30T14:30:40+00:00\",\"description\":\"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Viva-Connections.png\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Viva-Connections.png\",\"width\":1000,\"height\":333,\"caption\":\"Viva Connections\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/microsoft-viva-connections\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/.\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Offrez l&#8217;exp\u00e9rience Microsoft&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"name\":\"Powell\",\"description\":\"Intelligent Digital Workplace Suite\",\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\",\"name\":\"Powell\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"width\":969,\"height\":969,\"caption\":\"Powell\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PowellSoftware\",\"https:\\\/\\\/x.com\\\/powellsoftware\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBX2pfEUCxJQWCKOx9hvv8w\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/powell-software\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/d82fc37718810125131568da05cb0549\",\"name\":\"Yvonne Harris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"caption\":\"Yvonne Harris\"},\"description\":\"Yvonne Harris is the Brand and Communications Manager at Powell, where she spends her days proving that a corporate intranet doesn\u2019t have to look - or feel - like a relic from 1998. With over seven years of experience scaling B2B SaaS brands across Ireland and France, she specializes in turning \\\"boring\\\" workplace tech into human-centric stories. Based in Paris, Yvonne is a self-appointed detective of \\\"brand crimes\\\" and a firm believer that internal communication is a company\u2019s greatest competitive advantage. When she isn\u2019t leading global campaigns, she\u2019s likely advocating for the \\\"intranet glow-up\\\" your employees actually deserve.\",\"sameAs\":[\"https:\\\/\\\/www.powell-software.com\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yvonne-harris1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offrez l'exp\u00e9rience Microsoft Viva Connections en quelques clics","description":"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/","og_locale":"fr_FR","og_type":"article","og_title":"Offrez l'exp\u00e9rience Microsoft Viva Connections en quelques clics","og_description":"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che","og_url":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/","og_site_name":"Powell","article_publisher":"https:\/\/www.facebook.com\/PowellSoftware","article_published_time":"2021-06-06T10:03:50+00:00","article_modified_time":"2023-10-30T14:30:40+00:00","og_image":[{"width":1000,"height":333,"url":"http:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png","type":"image\/png"}],"author":"Yvonne Harris","twitter_card":"summary_large_image","twitter_creator":"@powellsoftware","twitter_site":"@powellsoftware","twitter_misc":{"Written by":"Yvonne Harris","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#article","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/"},"author":{"name":"Yvonne Harris","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/d82fc37718810125131568da05cb0549"},"headline":"Offrez l&#8217;exp\u00e9rience Microsoft Viva Connections en quelques clics","datePublished":"2021-06-06T10:03:50+00:00","dateModified":"2023-10-30T14:30:40+00:00","mainEntityOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/"},"wordCount":570,"publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/","url":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/","name":"Offrez l'exp\u00e9rience Microsoft Viva Connections en quelques clics","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#primaryimage"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png","datePublished":"2021-06-06T10:03:50+00:00","dateModified":"2023-10-30T14:30:40+00:00","description":"Microsoft Viva Connections est d\u00e9sormais disponible et pr\u00eat \u00e0 \u00eatre mis en \u0153uvre dans votre Digital Workplace. Powell Software, vous facilite la t\u00e2che","breadcrumb":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#primaryimage","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2021\/06\/Viva-Connections.png","width":1000,"height":333,"caption":"Viva Connections"},{"@type":"BreadcrumbList","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/microsoft-viva-connections\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powell-software.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/powell-software.com\/fr\/resources\/.\/blog\/"},{"@type":"ListItem","position":3,"name":"Offrez l&#8217;exp\u00e9rience Microsoft&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/powell-software.com\/fr\/#website","url":"https:\/\/powell-software.com\/fr\/","name":"Powell","description":"Intelligent Digital Workplace Suite","publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powell-software.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/powell-software.com\/fr\/#organization","name":"Powell","url":"https:\/\/powell-software.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","width":969,"height":969,"caption":"Powell"},"image":{"@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PowellSoftware","https:\/\/x.com\/powellsoftware","https:\/\/www.youtube.com\/channel\/UCBX2pfEUCxJQWCKOx9hvv8w","https:\/\/fr.linkedin.com\/company\/powell-software"]},{"@type":"Person","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/d82fc37718810125131568da05cb0549","name":"Yvonne Harris","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","caption":"Yvonne Harris"},"description":"Yvonne Harris is the Brand and Communications Manager at Powell, where she spends her days proving that a corporate intranet doesn\u2019t have to look - or feel - like a relic from 1998. With over seven years of experience scaling B2B SaaS brands across Ireland and France, she specializes in turning \"boring\" workplace tech into human-centric stories. Based in Paris, Yvonne is a self-appointed detective of \"brand crimes\" and a firm believer that internal communication is a company\u2019s greatest competitive advantage. When she isn\u2019t leading global campaigns, she\u2019s likely advocating for the \"intranet glow-up\" your employees actually deserve.","sameAs":["https:\/\/www.powell-software.com","https:\/\/www.linkedin.com\/in\/yvonne-harris1\/"]}]}},"_links":{"self":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/45982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/comments?post=45982"}],"version-history":[{"count":0,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/45982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media\/67245"}],"wp:attachment":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media?parent=45982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/categories?post=45982"},{"taxonomy":"audiences","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/audiences?post=45982"},{"taxonomy":"interests","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/interests?post=45982"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/products?post=45982"},{"taxonomy":"zones","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/zones?post=45982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}