{"id":36383,"date":"2020-04-01T14:57:03","date_gmt":"2020-04-01T13:57:03","guid":{"rendered":"https:\/\/powell-software.com\/?p=36383"},"modified":"2023-03-10T15:28:01","modified_gmt":"2023-03-10T14:28:01","slug":"rester-productif-en-teletravail-4-conseils-et-astuces","status":"publish","type":"post","link":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/","title":{"rendered":"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces"},"content":{"rendered":"<p style=\"text-align: justify;\">Il n&#8217;y a pas si longtemps, le <b>t\u00e9l\u00e9travail<\/b> \u00e9tait consid\u00e9r\u00e9 comme une nouveaut\u00e9. Quelques chanceux pouvaient profiter des avantages du <b>travail<\/b> \u00e0 domicile, mais seulement s&#8217;ils avaient un emploi \u00e0 distance. Mais <a href=\"https:\/\/www.cnbc.com\/2020\/03\/23\/what-coronavirus-means-for-the-future-of-work-from-home.html\">le nombre de personnes travaillant de chez eux n&#8217;a cess\u00e9 d&#8217;augmenter, jusqu\u2019\u00e0 un rythme de 10 %<\/a> par an au cours de la derni\u00e8re d\u00e9cennie. En 2018, <a href=\"https:\/\/www.cnbc.com\/2018\/05\/30\/70-percent-of-people-globally-work-remotely-at-least-once-a-week-iwg-study.html\">70 % des salari\u00e9s du monde entier travaillaient<\/a> \u00e0 distance au moins une fois par semaine.<\/p>\n<p style=\"text-align: justify;\">Cependant, les r\u00e9cents \u00e9v\u00e9nements mondiaux ont entra\u00een\u00e9 un changement majeur dans le travail \u00e0 distance. Lorsque la pand\u00e9mie de coronavirus a contraint de nombreuses \u00e9conomies nationales \u00e0 un arr\u00eat quasi total, d\u00e9clenchant l\u2019obligation de <b>t\u00e9l\u00e9-travailler<\/b> sur les cinq continents, les <b>entreprises<\/b> se sont retrouv\u00e9es sans autre choix que de s\u2019\u00e9quiper de Digital Workplaces &#8211; souvent avec seulement quelques heures ou quelques jours de pr\u00e9paration. Selon les experts, la crise pourrait bien \u00eatre le tournant n\u00e9cessaire pour que les <b>entreprises<\/b> prennent pleinement conscience que le <b>t\u00e9l\u00e9travail<\/b> est un mode d\u2019organisation incontournable dans notre \u00e9conomie internationale.<\/p>\n<p style=\"text-align: justify;\">Cela dit, cette nouvelle transition du bureau traditionnel vers le bureau \u00e0 domicile n&#8217;a pas \u00e9t\u00e9 sans difficult\u00e9s, en particulier pour les <b>entreprises<\/b> et les employ\u00e9s qui n&#8217;avaient pas encore l&#8217;exp\u00e9rience du home office. Mais m\u00eame avec peu de temps pour se pr\u00e9parer, il existe encore des mesures que les entreprises peuvent mettre en place rapidement pour faciliter le travail \u00e0 domicile et la mobilit\u00e9 de leurs employ\u00e9s.<\/p>\n<h2 style=\"text-align: center;\">Les d\u00e9fis du <b>t\u00e9l\u00e9travail<\/b><\/h2>\n<p style=\"text-align: justify;\">Que le <b>travail <\/b>\u00e0 distance soit un projet \u00e0 long terme pour votre entreprise ou une simple solution temporaire, la p\u00e9riode d&#8217;adaptation peut r\u00e9v\u00e9ler des obstacles. Voici quelques-uns des challenges que vous pourriez constater avec vos collaborateurs :<\/p>\n<h3 style=\"text-align: justify;\">Rester connect\u00e9<\/h3>\n<p style=\"text-align: justify;\">\u00c0 bien des \u00e9gards, le <b>t\u00e9l\u00e9travail <\/b>permet aux employ\u00e9s de rester connect\u00e9s mieux que jamais. Cela est d\u00fb aux nombreuses formes de communications disponibles sur la Digital Workplace, telles que la messagerie instantan\u00e9e, la vid\u00e9oconf\u00e9rence et les fils de discussion sp\u00e9cifiques \u00e0 un projet.<\/p>\n<p style=\"text-align: justify;\">Mais les travailleurs \u00e0 domicile peuvent avoir l&#8217;impression de passer \u00e0 c\u00f4t\u00e9 des connexions utiles qui d\u00e9coulent du travail dans un bureau partag\u00e9. <a href=\"https:\/\/www.fastcompany.com\/3051518\/the-science-of-when-you-need-in-person-communication\">La science d\u00e9montre<\/a> que le cerveau enregistre beaucoup mieux le non-verbal et qu\u2019il est une part essentielle de la communication pour \u00e9tablir la confiance et transmettre des \u00e9motions. Un chercheur a d\u00e9couvert que 93% de notre communication est non verbale. Pour donner un exemple, une \u00e9tude de Harvard et de l&#8217;Universit\u00e9 de Chicago a prouv\u00e9 que les n\u00e9gociations commerciales donnaient de meilleurs r\u00e9sultats lorsque les parties concern\u00e9es se serraient la main.<\/p>\n<p style=\"text-align: justify;\">A l\u2019inverse, certains employ\u00e9s \u00e0 domicile peuvent avoir l&#8217;impression de rester trop connect\u00e9s. Il est difficile de tracer la ligne entre le travail et la vie priv\u00e9e lorsque les deux activit\u00e9s se d\u00e9roulent dans le m\u00eame espace. Cela peut conduire au stress et \u00e0 l&#8217;\u00e9puisement professionnel si les courriels, les messages instantan\u00e9s et autres communications arrivent \u00e0 toute heure de la journ\u00e9e.<\/p>\n<h3 style=\"text-align: justify;\">Collaborer efficacement<\/h3>\n<p style=\"text-align: justify;\">L&#8217;apprentissage de nouveaux modes de communication cr\u00e9e \u00e9galement des d\u00e9fis pour une \u00e9quipe qui doit collaborer \u00e0 distance efficacement. Le <a href=\"https:\/\/hbr.org\/2018\/02\/how-to-collaborate-effectively-if-your-team-is-remote\">Harvard Business Review<\/a> identifie trois types de distance \u00e0 surmonter pour am\u00e9liorer la collaboration au sein d&#8217;une \u00e9quipe dispers\u00e9e : physique, op\u00e9rationnelle et d&#8217;affinit\u00e9. La distance physique, bien s\u00fbr, fait r\u00e9f\u00e9rence \u00e0 la g\u00e9ographie et au temps entre les membres de l&#8217;\u00e9quipe, tandis que la distance op\u00e9rationnelle est utilis\u00e9e pour d\u00e9crire les diff\u00e9rentes tailles et capacit\u00e9s des \u00e9quipes. La distance d&#8217;affinit\u00e9 est li\u00e9e aux valeurs et \u00e0 la confiance.<\/p>\n<p style=\"text-align: justify;\">Entre ces trois types de distance, vous remarquerez peut-\u00eatre que les employ\u00e9s ont plus de difficult\u00e9s que d&#8217;habitude \u00e0 collaborer sur des projets. Il est possible de surmonter ce probl\u00e8me avec les bons syst\u00e8mes et protocoles, dont nous parlerons plus loin.<\/p>\n<h3 style=\"text-align: justify;\">Trouver la bonne information<\/h3>\n<p style=\"text-align: justify;\">L&#8217;un des principaux avantages d&#8217;un espace de travail virtuel est qu&#8217;il permet de rassembler en un seul endroit toutes les informations, les documents et les communications de l&#8217;entreprise. Toutefois, au fil du temps, l&#8217;entreprise se d\u00e9veloppe et de nouvelles informations s&#8217;ajoutent chaque jour. Le volume m\u00eame des \u00e9l\u00e9ments \u00e0 passer au crible peut rendre extr\u00eamement difficile pour les employ\u00e9s de trouver ce dont ils ont besoin au moment o\u00f9 ils en ont besoin.<\/p>\n<p style=\"text-align: justify;\">Comment pouvez-vous vous assurer que votre personnel \u00e9loign\u00e9 sera en mesure de trouver les bonnes informations sur votre Digital Workplace ? Tout d\u00e9pend de <a href=\"https:\/\/powell-software.com\/fr\/gouvernance-de-microsoft-teams\/\">la mise en place de politiques de gouvernance<\/a> d\u00e8s le d\u00e9but du processus. Ces protocoles organisationnels garantiront que toutes les nouvelles informations sont ajout\u00e9es de mani\u00e8re strat\u00e9gique afin que toute personne qui en a besoin puisse y acc\u00e9der \u00e0 nouveau.<\/p>\n<h3 style=\"text-align: justify;\">G\u00e9rer la s\u00e9curit\u00e9<\/h3>\n<p style=\"text-align: justify;\">Les donn\u00e9es et informations exclusives de votre entreprise sont son plus grand atout. Lorsque votre entreprise travaille dans un lieu physique, il est facile de contenir des documents priv\u00e9s dans les murs de ses bureaux. Mais le travail \u00e0 distance permet de diffuser ces informations dans le monde entier, ce qui limite consid\u00e9rablement le contr\u00f4le que vous avez sur tous les appareils utilis\u00e9s par les employ\u00e9s \u00e0 distance.<\/p>\n<p style=\"text-align: justify;\">Les dispositifs de s\u00e9curit\u00e9 sont l&#8217;une des choses les plus importantes \u00e0 rechercher dans les outils de travail \u00e0 distance ou en mobilit\u00e9. Les employ\u00e9s qui travaillent \u00e0 domicile doivent disposer de protocoles en cas de perte ou de vol de leurs appareils, en particulier lorsque ces appareils quittent fr\u00e9quemment le bureau \u00e0 domicile et sont transport\u00e9s dans des lieux tels que les transports publics, les caf\u00e9s et les espaces de coworking.<\/p>\n<p>&nbsp;<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-node hs-cta-fef6c75d-0e76-42ec-9519-74c5d8565004\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/hubspot-cta-redirect-eu1-prod.s3.amazonaws.com\/cta\/redirect\/26290363\/fef6c75d-0e76-42ec-9519-74c5d8565004\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" id=\"hs-cta-img-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/hubspot-no-cache-eu1-prod.s3.amazonaws.com\/cta\/default\/26290363\/fef6c75d-0e76-42ec-9519-74c5d8565004.png\" alt=\"FR - Whitepaper : Remote Work\" width=\"1000\" height=\"333\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js-eu1.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(26290363, 'fef6c75d-0e76-42ec-9519-74c5d8565004', {\"useNewLoader\":\"true\",\"region\":\"eu1\"}); <\/script><\/span><\/p>\n<p><!-- end HubSpot Call-to-Action Code --><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">Faire de l&#8217;exp\u00e9rience home office un succ\u00e8s<\/h2>\n<p style=\"text-align: justify;\">Maintenant que nous comprenons les d\u00e9fis du travail \u00e0 distance, nous pouvons commencer \u00e0 examiner les diff\u00e9rentes solutions qui peuvent aider \u00e0 les surmonter. Voici quatre conseils que vous pouvez mettre en place d\u00e8s maintenant pour que le t\u00e9l\u00e9travail soit plus efficace :<\/p>\n<h3 style=\"text-align: justify;\">Choisir les bons outils<\/h3>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/powell-software.com\/fr\/outils-employes-mobiles\/\">Les outils de travail \u00e0 distance<\/a> sont votre meilleur atout pour surmonter les difficult\u00e9s li\u00e9es au travail chez soi. Les bons outils auront des fonctionnalit\u00e9s int\u00e9gr\u00e9es qui rendront la gestion de la communication, de la collaboration et de la s\u00e9curit\u00e9 simple, m\u00eame pour ceux qui n&#8217;ont aucune formation informatique.<\/p>\n<p style=\"text-align: justify;\">Diff\u00e9rents outils de communication permettent \u00e0 votre \u00e9quipe de collaborer par messagerie instantan\u00e9e, par appel vocal ou vid\u00e9o, et m\u00eame directement sur des documents sp\u00e9cifiques \u00e0 un projet. Cela vous donne la possibilit\u00e9 de choisir le type de communication le plus efficace pour chaque sc\u00e9nario. Par exemple, les r\u00e9unions d&#8217;\u00e9quipe qui auraient normalement lieu en personne peuvent facilement \u00eatre men\u00e9es par appel vid\u00e9o ce qui permet aux membres de se visualiser et de communiquer entre eux comme s&#8217;ils \u00e9taient dans la m\u00eame pi\u00e8ce. D&#8217;autre part, des messages moins urgents peuvent \u00eatre affich\u00e9s dans un chat de groupe pour que les membres puissent y r\u00e9pondre \u00e0 leur convenance.<\/p>\n<h3 style=\"text-align: justify;\">Respecter votre calendrier<\/h3>\n<p style=\"text-align: justify;\">Dans un bureau, vous avez tr\u00e8s probablement un horaire g\u00e9n\u00e9ral que la plupart des employ\u00e9s respectent : arriver \u00e0 9 heures, prendre une heure de pause d\u00e9jeuner vers midi ou 13 heures, et partir en fin de journ\u00e9e \u00e0 18h30. Les diff\u00e9rentes \u00e9quipes peuvent avoir des r\u00e9unions quotidiennes ou hebdomadaires programm\u00e9es \u00e0 des heures fixes, ou des cr\u00e9neaux horaires sp\u00e9cifiques consacr\u00e9s \u00e0 des t\u00e2ches distinctes tout au long de la journ\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Bien que le travail \u00e0 distance offre aux employ\u00e9s une plus grande flexibilit\u00e9 pour cr\u00e9er un horaire qui leur convient le mieux, le respect d&#8217;une certaine forme d&#8217;horaire est toujours une bonne id\u00e9e pour aider \u00e0 cr\u00e9er une structure pour ceux qui travaillent \u00e0 domicile. Vous pouvez par exemple d\u00e9finir une p\u00e9riode de la journ\u00e9e pendant laquelle tous les employ\u00e9s d&#8217;une \u00e9quipe doivent \u00eatre en ligne et disponibles pour r\u00e9pondre aux appels ou aux messages.<\/p>\n<p style=\"text-align: justify;\">Lorsque vous cr\u00e9ez un horaire pour votre \u00e9quipe \u00e0 distance, assurez-vous qu&#8217;il est minimal et qu&#8217;il se limite aux \u00e9l\u00e9ments absolument n\u00e9cessaires. Un horaire trop charg\u00e9 risque de donner \u00e0 vos employ\u00e9s l&#8217;impression d&#8217;\u00eatre microg\u00e9r\u00e9s et de leur enlever les avantages du t\u00e9l\u00e9travail Bien entendu, assurez-vous de d\u00e9finir clairement les attentes de tous les employ\u00e9s concern\u00e9s.<\/p>\n<h3 style=\"text-align: justify;\">Encourager la culture d&#8217;entreprise<\/h3>\n<p style=\"text-align: justify;\">La camaraderie au bureau et les valeurs de leadership jouent toutes deux un r\u00f4le important dans la culture d&#8217;entreprise.\u00a0 Une fois que votre entreprise a adopt\u00e9 le t\u00e9l\u00e9travail, il existe de nombreuses fa\u00e7ons de continuer \u00e0 faciliter et \u00e0 d\u00e9velopper la culture.<\/p>\n<p style=\"text-align: justify;\">L&#8217;exp\u00e9rience que les employ\u00e9s acqui\u00e8rent en acc\u00e9dant \u00e0 votre Digital Workplace est un \u00e9l\u00e9ment essentiel de l&#8217;introduction de la culture d&#8217;entreprise en home office. <a href=\"https:\/\/powell-software.com\/fr\/5-raisons-de-lancer-votre-digital-workplace-en-2020\/\">La personnalisation de votre portail d&#8217;entreprise<\/a> avec un logo et une palette de couleurs est un excellent moyen de donner \u00e0 votre Digital Workplace l&#8217;impression d&#8217;\u00eatre un lieu de travail physique. Vous pouvez \u00e9galement profiter de widgets pour afficher les mises \u00e0 jour et les messages de l&#8217;entreprise ou directement de la direction, ce qui encourage et renforce les objectifs de l&#8217;entreprise.<\/p>\n<p style=\"text-align: justify;\">La mani\u00e8re dont vous utilisez vos outils de travail \u00e0 distance a \u00e9galement un impact sur la culture de l&#8217;entreprise. Pendant la pand\u00e9mie de coronavirus, par exemple, de nombreuses \u00e9quipes ont souhait\u00e9 utiliser les appels vid\u00e9o de groupe pour organiser des pauses caf\u00e9 ou des happy hours pour toute l&#8217;entreprise, comme cela se d\u00e9roulerait normalement au bureau. Vous pouvez \u00e9galement d\u00e9signer des canaux dans les outils de communication <a href=\"https:\/\/products.office.com\/fr-fr\/microsoft-teams\/group-chat-software\">comme Microsoft Teams<\/a> pour des discussions hors sujet, en donnant aux employ\u00e9s un endroit o\u00f9 ils peuvent se retrouver autour d&#8217;anecdotes personnelles, d&#8217;int\u00e9r\u00eats communs ou m\u00eame de m\u00e8mes amusants.<\/p>\n<h3 style=\"text-align: justify;\">Communiquer, communiquer, communiquer<\/h3>\n<p style=\"text-align: justify;\">Alors que votre entreprise continue d&#8217;adopter le travail \u00e0 distance, nous avons un dernier conseil \u00e0 vous donner : communiquez. V\u00e9rifiez r\u00e9guli\u00e8rement aupr\u00e8s de votre \u00e9quipe, en demandant des mises \u00e0 jour, ou en vous int\u00e9ressant \u00e0 la fa\u00e7on dont le travail \u00e0 domicile se d\u00e9roule pour eux. Consacrez du temps \u00e0 la collecte de suggestions et \u00e0 la mise en \u0153uvre de nouvelles politiques en fonction des r\u00e9actions que vous recevez. N&#8217;ayez pas peur de trop communiquer ; il vaut bien mieux communiquer trop que pas assez.<\/p>\n<p style=\"text-align: justify;\">En fin de compte, le <span id=\"p490\"><b>t\u00e9l\u00e9travail<\/b><\/span> consiste \u00e0 faire passer l&#8217;employ\u00e9 en premier. L&#8217;efficacit\u00e9 de votre initiative de travail \u00e0 domicile est directement li\u00e9e \u00e0 la satisfaction des employ\u00e9s concern\u00e9s. En mettant en place les bons outils et la bonne structure, vous donnerez \u00e0 votre \u00e9quipe les ressources dont elle a besoin pour communiquer et faire son travail plus efficacement.<\/p>\n<p style=\"text-align: justify;\"><span id=\"p490\">Et vous, \u00eates vous plut\u00f4t un pro du <b>t\u00e9l\u00e9travail<\/b> ou encore novice ?<\/span><span id=\"p494\">\u00a0Apr\u00e8s ces quelques lignes, nous sommes s\u00fbrs que <b>t\u00e9l\u00e9travail<\/b> n&#8217;aura plus de secrets pour vous.<\/span><span id=\"p492\">\u00a0Vous avez toutes les cl\u00e9s du succ\u00e8s !<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-node hs-cta-fef6c75d-0e76-42ec-9519-74c5d8565004\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/hubspot-cta-redirect-eu1-prod.s3.amazonaws.com\/cta\/redirect\/26290363\/fef6c75d-0e76-42ec-9519-74c5d8565004\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" id=\"hs-cta-img-fef6c75d-0e76-42ec-9519-74c5d8565004\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/hubspot-no-cache-eu1-prod.s3.amazonaws.com\/cta\/default\/26290363\/fef6c75d-0e76-42ec-9519-74c5d8565004.png\" alt=\"FR - Whitepaper : Remote Work\" width=\"1000\" height=\"333\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js-eu1.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(26290363, 'fef6c75d-0e76-42ec-9519-74c5d8565004', {\"useNewLoader\":\"true\",\"region\":\"eu1\"}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que le t\u00e9l\u00e9travail fasse parti de votre organisation de travail sur le long terme ou qu&#8217;il soit juste une solution temporaire, nous vous livrons toutes les cl\u00e9s pour accompagner vos employ\u00e9s en home office.<\/p>\n","protected":false},"author":32,"featured_media":60105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1671],"audiences":[1686,1687],"interests":[1685],"products":[],"zones":[],"class_list":["post-36383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","audiences-collaborateurs","audiences-ressources-humaines","interests-teletravail-travail-hybride"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell<\/title>\n<meta name=\"description\" content=\"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell\" \/>\n<meta property=\"og:description\" content=\"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/\" \/>\n<meta property=\"og:site_name\" content=\"Powell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PowellSoftware\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-01T13:57:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-10T14:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png\" \/>\n\t<meta property=\"og:image:width\" content=\"970\" \/>\n\t<meta property=\"og:image:height\" content=\"324\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yvonne Harris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:site\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yvonne Harris\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/\"},\"author\":{\"name\":\"Yvonne Harris\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/d82fc37718810125131568da05cb0549\"},\"headline\":\"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces\",\"datePublished\":\"2020-04-01T13:57:03+00:00\",\"dateModified\":\"2023-03-10T14:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/\"},\"wordCount\":1923,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Remote-Working-Tips.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/\",\"name\":\"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Remote-Working-Tips.png\",\"datePublished\":\"2020-04-01T13:57:03+00:00\",\"dateModified\":\"2023-03-10T14:28:01+00:00\",\"description\":\"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Remote-Working-Tips.png\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Remote-Working-Tips.png\",\"width\":970,\"height\":324},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/blog\\\/rester-productif-en-teletravail-4-conseils-et-astuces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/resources\\\/.\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rester productif en t\u00e9l\u00e9travail&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"name\":\"Powell\",\"description\":\"Intelligent Digital Workplace Suite\",\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#organization\",\"name\":\"Powell\",\"url\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"width\":969,\"height\":969,\"caption\":\"Powell\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PowellSoftware\",\"https:\\\/\\\/x.com\\\/powellsoftware\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBX2pfEUCxJQWCKOx9hvv8w\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/powell-software\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/fr\\\/#\\\/schema\\\/person\\\/d82fc37718810125131568da05cb0549\",\"name\":\"Yvonne Harris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g\",\"caption\":\"Yvonne Harris\"},\"description\":\"Yvonne Harris is the Brand and Communications Manager at Powell, where she spends her days proving that a corporate intranet doesn\u2019t have to look - or feel - like a relic from 1998. With over seven years of experience scaling B2B SaaS brands across Ireland and France, she specializes in turning \\\"boring\\\" workplace tech into human-centric stories. Based in Paris, Yvonne is a self-appointed detective of \\\"brand crimes\\\" and a firm believer that internal communication is a company\u2019s greatest competitive advantage. When she isn\u2019t leading global campaigns, she\u2019s likely advocating for the \\\"intranet glow-up\\\" your employees actually deserve.\",\"sameAs\":[\"https:\\\/\\\/www.powell-software.com\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yvonne-harris1\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell","description":"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/","og_locale":"fr_FR","og_type":"article","og_title":"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell","og_description":"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.","og_url":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/","og_site_name":"Powell","article_publisher":"https:\/\/www.facebook.com\/PowellSoftware","article_published_time":"2020-04-01T13:57:03+00:00","article_modified_time":"2023-03-10T14:28:01+00:00","og_image":[{"width":970,"height":324,"url":"http:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png","type":"image\/png"}],"author":"Yvonne Harris","twitter_card":"summary_large_image","twitter_creator":"@powellsoftware","twitter_site":"@powellsoftware","twitter_misc":{"Written by":"Yvonne Harris","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#article","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/"},"author":{"name":"Yvonne Harris","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/d82fc37718810125131568da05cb0549"},"headline":"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces","datePublished":"2020-04-01T13:57:03+00:00","dateModified":"2023-03-10T14:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/"},"wordCount":1923,"commentCount":0,"publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png","articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/","url":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/","name":"Rester productif en t\u00e9l\u00e9travail : 4 conseils et astuces - Powell","isPartOf":{"@id":"https:\/\/powell-software.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#primaryimage"},"image":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png","datePublished":"2020-04-01T13:57:03+00:00","dateModified":"2023-03-10T14:28:01+00:00","description":"Que le t\u00e9l\u00e9travail fasse parti de votre plan sur le long ou court terme, voici les cl\u00e9s pour accompagner vos employ\u00e9s en home office.","breadcrumb":{"@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#primaryimage","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2020\/03\/Remote-Working-Tips.png","width":970,"height":324},{"@type":"BreadcrumbList","@id":"https:\/\/powell-software.com\/fr\/resources\/blog\/rester-productif-en-teletravail-4-conseils-et-astuces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powell-software.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/powell-software.com\/fr\/resources\/.\/blog\/"},{"@type":"ListItem","position":3,"name":"Rester productif en t\u00e9l\u00e9travail&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/powell-software.com\/fr\/#website","url":"https:\/\/powell-software.com\/fr\/","name":"Powell","description":"Intelligent Digital Workplace Suite","publisher":{"@id":"https:\/\/powell-software.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powell-software.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/powell-software.com\/fr\/#organization","name":"Powell","url":"https:\/\/powell-software.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","width":969,"height":969,"caption":"Powell"},"image":{"@id":"https:\/\/powell-software.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PowellSoftware","https:\/\/x.com\/powellsoftware","https:\/\/www.youtube.com\/channel\/UCBX2pfEUCxJQWCKOx9hvv8w","https:\/\/fr.linkedin.com\/company\/powell-software"]},{"@type":"Person","@id":"https:\/\/powell-software.com\/fr\/#\/schema\/person\/d82fc37718810125131568da05cb0549","name":"Yvonne Harris","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56f8ba3138731615b6df4ff4c0ab9a451aa93de41c8752647097b82b2188135a?s=96&d=mm&r=g","caption":"Yvonne Harris"},"description":"Yvonne Harris is the Brand and Communications Manager at Powell, where she spends her days proving that a corporate intranet doesn\u2019t have to look - or feel - like a relic from 1998. With over seven years of experience scaling B2B SaaS brands across Ireland and France, she specializes in turning \"boring\" workplace tech into human-centric stories. Based in Paris, Yvonne is a self-appointed detective of \"brand crimes\" and a firm believer that internal communication is a company\u2019s greatest competitive advantage. When she isn\u2019t leading global campaigns, she\u2019s likely advocating for the \"intranet glow-up\" your employees actually deserve.","sameAs":["https:\/\/www.powell-software.com","https:\/\/www.linkedin.com\/in\/yvonne-harris1\/"]}]}},"_links":{"self":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/36383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/comments?post=36383"}],"version-history":[{"count":0,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/posts\/36383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media\/60105"}],"wp:attachment":[{"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/media?parent=36383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/categories?post=36383"},{"taxonomy":"audiences","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/audiences?post=36383"},{"taxonomy":"interests","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/interests?post=36383"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/products?post=36383"},{"taxonomy":"zones","embeddable":true,"href":"https:\/\/powell-software.com\/fr\/wp-json\/wp\/v2\/zones?post=36383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}