{"id":160346,"date":"2026-08-11T15:28:37","date_gmt":"2026-08-11T13:28:37","guid":{"rendered":"https:\/\/powell-software.com\/?p=160346"},"modified":"2026-08-24T11:15:32","modified_gmt":"2026-08-24T09:15:32","slug":"messe-muenchen","status":"publish","type":"post","link":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/","title":{"rendered":"Messe M\u00fcnchen: Ein Intranet-Relaunch mit Wiedererkennungswert"},"content":{"rendered":"<div style=\"font-family: 'Lexend', sans-serif; line-height: 1.7; color: #003c49; font-size: 16.5px; max-width: 100%; box-sizing: border-box; overflow-x: hidden;\">\n<div style=\"font-family: 'Lexend', sans-serif; line-height: 1.7; color: #003c49; font-size: 16.5px; max-width: 100%; box-sizing: border-box; overflow-x: hidden;\">\n<div style=\"background-color: #f4f4f4; padding: 20px; border-radius: 10px; width: 100%; box-sizing: border-box; display: flex; flex-wrap: wrap; justify-content: center; align-items: stretch; gap: 12px; margin: 20px 0;\">\n<div style=\"background: white; border-radius: 8px; overflow: hidden; min-width: 130px; text-align: center; box-sizing: border-box; box-shadow: 0 1px 4px rgba(0,0,0,0.08); flex: 1;\">\n<div style=\"background: #e55393; height: 5px; width: 100%;\"><\/div>\n<div style=\"padding: 14px 20px; font-size: 16px; color: #003c49; overflow-wrap: break-word;\"><strong>Mitarbeitende:<\/strong><br \/>\n624<\/div>\n<\/div>\n<div style=\"background: white; border-radius: 8px; overflow: hidden; min-width: 130px; text-align: center; box-sizing: border-box; box-shadow: 0 1px 4px rgba(0,0,0,0.08); flex: 1;\">\n<div style=\"background: #2EDFCA; height: 5px; width: 100%;\"><\/div>\n<div style=\"padding: 14px 20px; font-size: 16px; color: #003c49; overflow-wrap: break-word;\"><strong>Branche:<\/strong><br \/>\nMesse &amp; Veranstaltungen<\/div>\n<\/div>\n<div style=\"background: white; border-radius: 8px; overflow: hidden; min-width: 130px; text-align: center; box-sizing: border-box; box-shadow: 0 1px 4px rgba(0,0,0,0.08); flex: 1;\">\n<div style=\"background: #97FFBA; height: 5px; width: 100%;\"><\/div>\n<div style=\"padding: 14px 20px; font-size: 16px; color: #003c49; overflow-wrap: break-word;\"><strong>Standort:<\/strong><br \/>\nDeutschland<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">Der Kunde im \u00dcberblick<\/h2>\n<p style=\"margin: 0 0 18px 0;\"><a style=\"color: #e55393; text-decoration: none; font-weight: 600;\" href=\"https:\/\/messe-muenchen.de\/de\/\">Messe M\u00fcnchen<\/a> ist eines der weltweit f\u00fchrenden Messeveranstaltungsunternehmen und agiert in einem dynamischen, \u00f6ffentlichkeitswirksamen Umfeld. Mit 624 Mitarbeitenden in Deutschland sind klare interne Kommunikation und reibungslose Koordination \u00fcber Teams und Veranstaltungen hinweg unverzichtbar.<\/p>\n<p style=\"margin: 0 0 18px 0;\">Um den digitalen Arbeitsplatz zu modernisieren, wechselte Messe M\u00fcnchen von einer veralteten SharePoint-Umgebung zu SharePoint Online Modern, erg\u00e4nzt durch <a style=\"color: #e55393; text-decoration: none; font-weight: 600;\" href=\"https:\/\/powell-software.com\/products\/powell-intranet\/\">Powell<\/a>. Das Ziel war klar: ein visuell markantes, intuitives Intranet, das den Arbeitsalltag unterst\u00fctzt und die weiterentwickelte Markenidentit\u00e4t des Unternehmens widerspiegelt.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">Die Ausgangslage<\/h2>\n<p>&nbsp;<\/p>\n<div style=\"background: #f0f7f8; border: 2px solid #003C49; padding: 24px; border-radius: 12px; margin: 30px 0; position: relative; overflow: hidden; color: #003c49; box-sizing: border-box;\">\n<p><span style=\"font-size: 80px; color: #2edfca; line-height: 0.5; position: absolute; top: 10px; left: 10px; opacity: 0.8;\">&#8220;<\/span><\/p>\n<p style=\"margin: 30px 0 10px 0; line-height: 1.6;\">Der Relaunch fand mitten in einer umfassenderen Rebranding-Initiative statt. Wir mussten unter Unsicherheit gestalten und mit einem reduzierten Farbspektrum ein dynamisches Erlebnis schaffen, das sich klar vom alten System abhob.<\/p>\n<p style=\"font-size: 13px; font-style: italic; margin-top: 10px;\">Messe M\u00fcnchen Intranet Relaunch<\/p>\n<div style=\"text-align: right; margin: 20px 0 0 0; border-top: 1px solid #003C49; padding-top: 10px;\"><strong style=\"color: #003c49; font-size: 18px; font-weight: 800; display: block;\">Messe M\u00fcnchen<\/strong><br \/>\n<span style=\"font-size: 14px; color: #336b74;\"><a style=\"color: #e55393; text-decoration: none; font-weight: 600;\" href=\"https:\/\/messe-muenchen.de\/de\/\">messe-muenchen.de<\/a><\/span><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0 0 18px 0;\">Der Relaunch fiel in eine Phase des umfassenden Rebrandings. Zentrale Elemente des neuen Corporate Designs, darunter die finale Farbpalette, befanden sich noch in der Entwicklung, w\u00e4hrend das Intranet-Projekt bereits lief. Das Team musste visuelle Entscheidungen kontinuierlich anpassen, sobald neue Markenrichtlinien verf\u00fcgbar wurden. Um den Zeitplan einzuhalten, begann die Arbeit mit zwei bereits best\u00e4tigten Blaut\u00f6nen als gestalterischer Grundlage. Die Herausforderung: mit bewusst reduziertem Farbspektrum ein ansprechendes, dynamisches Erlebnis schaffen.<\/p>\n<p style=\"margin: 0 0 18px 0;\">Ein weiteres Ziel war es, das neue Intranet klar vom bisherigen zu unterscheiden. Mitarbeitende sollten sofort erkennen: Das ist kein Update, das ist etwas Neues. Zus\u00e4tzliche Komplexit\u00e4t entstand durch die Integration zweier \u00e4hnlicher Inhaltskategorien, jeweils zwei verschiedene Arten von News und Veranstaltungen. Beide brauchten eine prominente Platzierung auf der Startseite, mussten aber visuell klar unterscheidbar und logisch strukturiert sein.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">Der Weg zur L\u00f6sung<\/h2>\n<p style=\"margin: 0 0 18px 0;\">Das neue Intranet wurde als \u00fcbersichtliche, strukturierte Umgebung gestaltet, die den Arbeitsalltag ohne visuelle \u00dcberladung unterst\u00fctzt. Die Oberfl\u00e4che wirkt minimalistisch, basiert aber auf sorgf\u00e4ltig durchdachten Struktur- und Designentscheidungen. Durch iteratives Prototyping wurden mehrere Versionen der Startseite direkt im System getestet.<\/p>\n<div style=\"display: flex; gap: 15px; margin: 30px 0; flex-wrap: wrap;\">\n<div style=\"flex: 1; min-width: 250px; background: #2EDFCA; padding: 20px; border-radius: 10px; color: #003c49; box-sizing: border-box; overflow-wrap: break-word; text-align: center;\"><img decoding=\"async\" style=\"width: 43px; height: auto; margin-bottom: 10px; display: block; margin-left: auto; margin-right: auto; max-width: 100%;\" src=\"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/01\/Generic-icon-1.png\" alt=\"\" \/><strong>Starke visuelle Identit\u00e4t<\/strong><br \/>\nSystematischer Einsatz eigener Templates und Headerbilder f\u00fcr jeden Bereich.<\/div>\n<div style=\"flex: 1; min-width: 250px; background: #97FFBA; padding: 20px; border-radius: 10px; color: #003c49; box-sizing: border-box; overflow-wrap: break-word; text-align: center;\"><img decoding=\"async\" style=\"width: 43px; height: auto; margin-bottom: 10px; display: block; margin-left: auto; margin-right: auto; max-width: 100%;\" src=\"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/01\/Generic-icon-2.png\" alt=\"\" \/><strong>Nutzererlebnis<\/strong><br \/>\nEinheitliche Seitenumbr\u00fcche, vergr\u00f6\u00dferte Schriften und \u00dcbersetzungsfunktion im Header.<\/div>\n<div style=\"flex: 1; min-width: 250px; background: #003C49; padding: 20px; border-radius: 10px; color: white; box-sizing: border-box; overflow-wrap: break-word; text-align: center;\"><img decoding=\"async\" style=\"width: 43px; height: auto; margin-bottom: 10px; display: block; margin-left: auto; margin-right: auto; max-width: 100%;\" src=\"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/01\/Generic-icon-3.png\" alt=\"\" \/><strong>Klare Struktur<\/strong><br \/>\nReduzierte Komplexit\u00e4t und intuitive Navigation f\u00fcr den t\u00e4glichen Einsatz.<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"margin: 0 0 18px 0;\">Zentrale Gestaltungsprinzipien waren:<\/p>\n<ul>\n<li>Eine konsistente visuelle Sprache, abgeleitet aus dem sich entwickelnden Corporate Design<\/li>\n<li>Auff\u00e4llige Startseitenelemente als Signal f\u00fcr einen echten Neuanfang<\/li>\n<li>Klare Hierarchien und intuitive Navigation<\/li>\n<li>Weniger Text zugunsten strukturierter visueller Orientierung<\/li>\n<li>Eigene Headerbilder f\u00fcr jeden Hauptnavigationsbereich<\/li>\n<li>Systematischer Einsatz von Seitenvorlagen f\u00fcr einheitliches Erscheinungsbild<\/li>\n<\/ul>\n<p style=\"margin: 0 0 18px 0;\">Zahlreiche Detailverbesserungen steigerten sowohl \u00c4sthetik als auch Nutzbarkeit. Seitenumbr\u00fcche und &#8220;Mehr anzeigen&#8221;-Buttons wurden visuell vereinheitlicht. \u00dcberschriftenfarben wurden an den prim\u00e4ren Markenton angepasst. Die \u00dcbersetzungsfunktion wurde in den Header verschoben f\u00fcr schnelleren Zugriff. Redundante Seitenheader wurden entfernt, um die Oberfl\u00e4che zu entlasten. Schriftgr\u00f6\u00dfen in der Hauptnavigation wurden f\u00fcr bessere Lesbarkeit vergr\u00f6\u00dfert.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"margin: 24px 0 8px 0; font-size: 22px; font-weight: bold; color: #004f5a;\">&#x1f4ca; Die Ergebnisse in Zahlen<\/h3>\n<div style=\"display: grid; grid-template-columns: repeat(3, 1fr); gap: 16px; margin: 20px 0; width: 100%; box-sizing: border-box;\">\n<div style=\"background: white; padding: 20px; border-radius: 8px; box-shadow: 0 2px 8px rgba(0,0,0,0.1); box-sizing: border-box; overflow-wrap: break-word;\"><strong style=\"color: #ef6da6; display: block; margin-bottom: 8px; font-size: 24px;\">+87,7%<\/strong><br \/>\n<span style=\"color: #555;\">Mehr Aufrufe zwischen dem ersten Monat und Januar<\/span><\/div>\n<div style=\"background: white; padding: 20px; border-radius: 8px; box-shadow: 0 2px 8px rgba(0,0,0,0.1); box-sizing: border-box; overflow-wrap: break-word;\"><strong style=\"color: #ef6da6; display: block; margin-bottom: 8px; font-size: 24px;\">81.000<\/strong><br \/>\n<span style=\"color: #555;\">Gesamte Seitenaufrufe (gegen\u00fcber zuvor 55.000)<\/span><\/div>\n<div style=\"background: white; padding: 20px; border-radius: 8px; box-shadow: 0 2px 8px rgba(0,0,0,0.1); box-sizing: border-box; overflow-wrap: break-word;\"><strong style=\"color: #ef6da6; display: block; margin-bottom: 8px; font-size: 24px;\">16.000+<\/strong><br \/>\n<span style=\"color: #555;\">Seitenaufrufe im ersten Monat von ca. 700 Nutzenden<\/span><\/div>\n<\/div>\n<p style=\"margin: 0 0 18px 0;\">Das Intranet startete am 9. Dezember 2025 als vollst\u00e4ndiger Neuaufbau auf einem neuen Technologie-Stack. Vertrauen musste schnell aufgebaut werden. Die stetig steigenden Nutzungszahlen best\u00e4tigen, dass Design und Usability-Ansatz bei den Mitarbeitenden ankamen. Die Gesamtaktivit\u00e4t stieg um 36,9 Prozent.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">Das sagen die Mitarbeitenden<\/h2>\n<p style=\"margin: 0 0 18px 0;\">Der Relaunch hat das Intranet zum t\u00e4glichen Begleiter gemacht. Mit klarer Informationsarchitektur und intuitiver Navigation sind wichtige Inhalte in Sekunden auffindbar. Visuelle Konsistenz und strukturierte Layouts reduzieren den kognitiven Aufwand und verbessern die Orientierung.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"background: white; padding: 30px; border-radius: 12px; margin: 30px 0; border-left: 6px solid #2EDFCA; box-shadow: 0 2px 8px rgba(0,0,0,0.1); box-sizing: border-box;\">\n<p style=\"margin: 0 0 15px 0; color: #003c49; font-size: 18px; font-style: italic; line-height: 1.8;\">&#8220;Jetzt finde ich alles mit wenigen Klicks und bin viel besser informiert. Das Intranet ist zu einem t\u00e4glichen Begleiter geworden, der meine Arbeit sp\u00fcrbar erleichtert.&#8221;<\/p>\n<p style=\"margin: 0; color: #555; font-weight: bold;\">\u2014 Mitarbeiterin \/ Mitarbeiter, Messe M\u00fcnchen<span style=\"color: #003c49;\">\u00a0<\/span><\/p>\n<\/div>\n<div style=\"background: white; padding: 30px; border-radius: 12px; margin: 30px 0; border-left: 6px solid #2EDFCA; box-shadow: 0 2px 8px rgba(0,0,0,0.1); box-sizing: border-box;\">\n<p style=\"margin: 0 0 15px 0; color: #003c49; font-size: 18px; font-style: italic; line-height: 1.8;\">&#8220;Der Relaunch bietet uns aus redaktioneller Sicht eine gro\u00dfe Bandbreite an Darstellungsm\u00f6glichkeiten, was sich auch in den Nutzungszahlen des Intranets widerspiegelt.&#8221;<\/p>\n<p style=\"margin: 0; color: #555; font-weight: bold;\">\u2014 Redaktionsteam, Messe M\u00fcnchen<\/p>\n<\/div>\n<p><img fetchpriority=\"low\" loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1371\" class=\"alignnone wp-image-157230 \" style=\"width: 865px; height: 463px; display: block; border-radius: 12px; margin: 30px 0px;\" src=\"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-scaled.png\" alt=\"Messe M\u00fcnchen Intranet Relaunch\" srcset=\"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-scaled.png 2560w, https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-480x257.png 480w, https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-1200x643.png 1200w, https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-768x411.png 768w, https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-1536x823.png 1536w, https:\/\/powell-software.com\/wp-content\/uploads\/2026\/04\/MESSE-MUNCHEN-1-2048x1097.png 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">Fazit<\/h2>\n<p style=\"margin: 0 0 18px 0;\">Der Intranet-Relaunch von Messe M\u00fcnchen zeigt: Gutes Design ist keine Dekoration, sondern Strategie. Durch die Verbindung von visueller Sprache, Informationsarchitektur und Nutzererlebnis in SharePoint Online Modern mit Powell entstand ein digitaler Arbeitsplatz, der intuitiv, markenkonform und zukunftsf\u00e4hig ist. Iteratives Prototyping, enge Zusammenarbeit und ein klarer Fokus auf Nutzbarkeit haben ein Intranet entstehen lassen, das visuelle Markenst\u00e4rke mit praktischem Alltags-Mehrwert verbindet.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"background: #cfffe0; padding: 30px; border-radius: 12px; margin: 30px 0; border-left: 6px solid #003C49; box-sizing: border-box;\">\n<h3 style=\"margin: 0 0 16px 0; color: #003c49; font-weight: bold;\">&#x2728; Auf den Punkt gebracht<\/h3>\n<ul style=\"margin: 0; padding-left: 20px; color: #003c49; line-height: 1.8;\">\n<li><strong>Design als Strategie:<\/strong> Eine starke visuelle Identit\u00e4t schafft Vertrauen und f\u00f6rdert die Plattformakzeptanz.<\/li>\n<li><strong>Iteratives Prototyping:<\/strong> Layouts direkt im System zu testen erm\u00f6glicht schnellere und nachhaltigere Entscheidungen.<\/li>\n<li><strong>Klarheit statt Komplexit\u00e4t:<\/strong> Weniger redundante Elemente und ein reduziertes Farbspektrum verbessern die Orientierung.<\/li>\n<\/ul>\n<\/div>\n<p>&nbsp;<\/p>\n<h2 style=\"margin: 40px 0 14px 0; font-size: 30px; line-height: 1.3; font-weight: 800; color: #003c49; border-left: 6px solid #e55393; padding-left: 12px;\">\u00dcber den Partner: HIRSCHTEC<\/h2>\n<p style=\"margin: 0 0 18px 0;\">Seit 2005 auf die Digitalisierung der internen Kommunikation und Zusammenarbeit spezialisiert, erhalten <a style=\"color: #e55393; text-decoration: none; font-weight: 600;\" href=\"https:\/\/hirschtec.eu\/hirschtec-group\/\">HIRSCHTEC<\/a>-Kunden alles aus einer Hand: von der Gesamtstrategie f\u00fcr den digitalen Arbeitsplatz \u00fcber die Einf\u00fchrung und Weiterentwicklung von Intranets, Mitarbeiter-Apps und digitalen Arbeitspl\u00e4tzen auf Basis von M365 bis hin zur Automatisierung von Workflows und Unterst\u00fctzung bei der digitalen F\u00fchrung.<\/p>\n<p>&nbsp;<\/p>\n<section style=\"background: linear-gradient(135deg, #CFFFE0 0%, #F0FEFC 100%); border-radius: 28px; padding: 40px; margin: 40px 0; display: flex; flex-wrap: wrap; align-items: center; justify-content: space-between; gap: 24px;\">\n<div style=\"max-width: 620px; flex: 1 1 320px;\">\n<p style=\"margin: 0 0 8px; color: #e55393; font-size: 13px; text-transform: uppercase; letter-spacing: 1.2px; font-weight: bold;\">\u00dcberzeugt von diesem Ergebnis?<\/p>\n<h2 style=\"margin: 0 0 12px; font-size: 30px; line-height: 1.25; color: #003c49; font-weight: bold;\">Entdecken Sie, was Powell f\u00fcr Ihre Organisation leisten kann.<\/h2>\n<p style=\"margin: 0; color: #315e66; font-size: 16px; line-height: 1.6;\">Ob erste Orientierung oder konkrete Demo \u2013 wir zeigen Ihnen, wie der richtige Einstieg in Ihr Digital Workplace mit Powell gelingt.<\/p>\n<\/div>\n<div style=\"display: flex; flex-direction: column; gap: 12px; width: 100%; max-width: 280px; box-sizing: border-box;\"><a style=\"display: block; box-sizing: border-box; width: 100%; text-align: center; background: #003C49; color: #ffffff; text-decoration: none; padding: 15px 26px; border-radius: 999px; font-weight: bold;\" href=\"https:\/\/powell-software.com\/de\/demo\/\">Demo vereinbaren<\/a><br \/>\n<a style=\"display: block; box-sizing: border-box; width: 100%; text-align: center; background: transparent; color: #003c49; text-decoration: none; padding: 13px 26px; border-radius: 999px; font-weight: bold; border: 2px solid #003C49;\" href=\"https:\/\/powell-software.com\/de\/produkte\/powell-intranet\/\">Produkt entdecken<\/a><\/div>\n<\/section>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&gt;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mitarbeitende: 624 Branche: Messe &amp; Veranstaltungen Standort: Deutschland &nbsp; Der Kunde im \u00dcberblick Messe M\u00fcnchen ist eines der weltweit f\u00fchrenden Messeveranstaltungsunternehmen und agiert in einem &hellip; <a href=\"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/\">Continued<\/a><\/p>\n","protected":false},"author":86,"featured_media":156531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2030],"audiences":[],"interests":[],"products":[1764],"zones":[],"class_list":["post-160346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erfolgsgeschichten","products-powell-intranet-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Messe M\u00fcnchen - Powell<\/title>\n<meta name=\"description\" content=\"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messe M\u00fcnchen - Powell\" \/>\n<meta property=\"og:description\" content=\"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/\" \/>\n<meta property=\"og:site_name\" content=\"Powell\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PowellSoftware\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-11T13:28:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-24T09:15:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"675\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lydia Schierig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:site\" content=\"@powellsoftware\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lydia Schierig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/\"},\"author\":{\"name\":\"Lydia Schierig\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#\\\/schema\\\/person\\\/13226a9d5264862c57f9255d78f3ff80\"},\"headline\":\"Messe M\u00fcnchen: Ein Intranet-Relaunch mit Wiedererkennungswert\",\"datePublished\":\"2026-08-11T13:28:37+00:00\",\"dateModified\":\"2026-08-24T09:15:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/\"},\"wordCount\":851,\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Messe-.png\",\"articleSection\":[\"Success stories\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/\",\"name\":\"Messe M\u00fcnchen - Powell\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Messe-.png\",\"datePublished\":\"2026-08-11T13:28:37+00:00\",\"dateModified\":\"2026-08-24T09:15:32+00:00\",\"description\":\"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Messe-.png\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Messe-.png\",\"width\":675,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/erfolgsgeschichten\\\/messe-muenchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/powell-software.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Success stories\",\"item\":\"https:\\\/\\\/powell-software.com\\\/de\\\/resources\\\/.\\\/erfolgsgeschichten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Messe M\u00fcnchen: Ein Intranet-Relaunch&hellip;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/powell-software.com\\\/de\\\/\",\"name\":\"Powell\",\"description\":\"Intelligent Digital Workplace Suite\",\"publisher\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/powell-software.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#organization\",\"name\":\"Powell\",\"url\":\"https:\\\/\\\/powell-software.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"contentUrl\":\"https:\\\/\\\/powell-software.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/favicon.webp\",\"width\":969,\"height\":969,\"caption\":\"Powell\"},\"image\":{\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PowellSoftware\",\"https:\\\/\\\/x.com\\\/powellsoftware\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBX2pfEUCxJQWCKOx9hvv8w\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/powell-software\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/powell-software.com\\\/de\\\/#\\\/schema\\\/person\\\/13226a9d5264862c57f9255d78f3ff80\",\"name\":\"Lydia Schierig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g\",\"caption\":\"Lydia Schierig\"},\"description\":\"B2B-Marketing trifft auf kulturelle Finesse: Lydia beweist, dass starker Content kein Selbstzweck ist, sondern Vertrauen schafft. Mit Erfahrung in den Bereichen LegalTech, Hospitality und SaaS hat sie Markenpr\u00e4senzen dort aufgebaut, wo Glaubw\u00fcrdigkeit alles ist. Bei Powell vereint sie deutsche Pr\u00e4zision mit Pariser Flair, um Kampagnen zu entwickeln, die echte Menschen erreichen. Ihr Fokus? Die Br\u00fccke zwischen Sales und Marketing zu schlagen, weil die besten Ergebnisse durch Teamarbeit entstehen. Wenn sie nicht gerade Strategien entwirft, erkundet sie die Stra\u00dfen von Paris, immer auf der Mission, den absolut besten Kaffee der Stadt zu finden.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/lydia-schierig\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messe M\u00fcnchen - Powell","description":"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/","og_locale":"de_DE","og_type":"article","og_title":"Messe M\u00fcnchen - Powell","og_description":"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.","og_url":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/","og_site_name":"Powell","article_publisher":"https:\/\/www.facebook.com\/PowellSoftware","article_published_time":"2026-08-11T13:28:37+00:00","article_modified_time":"2026-08-24T09:15:32+00:00","og_image":[{"width":675,"height":450,"url":"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png","type":"image\/png"}],"author":"Lydia Schierig","twitter_card":"summary_large_image","twitter_creator":"@powellsoftware","twitter_site":"@powellsoftware","twitter_misc":{"Written by":"Lydia Schierig","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#article","isPartOf":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/"},"author":{"name":"Lydia Schierig","@id":"https:\/\/powell-software.com\/de\/#\/schema\/person\/13226a9d5264862c57f9255d78f3ff80"},"headline":"Messe M\u00fcnchen: Ein Intranet-Relaunch mit Wiedererkennungswert","datePublished":"2026-08-11T13:28:37+00:00","dateModified":"2026-08-24T09:15:32+00:00","mainEntityOfPage":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/"},"wordCount":851,"publisher":{"@id":"https:\/\/powell-software.com\/de\/#organization"},"image":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png","articleSection":["Success stories"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/","url":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/","name":"Messe M\u00fcnchen - Powell","isPartOf":{"@id":"https:\/\/powell-software.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#primaryimage"},"image":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#primaryimage"},"thumbnailUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png","datePublished":"2026-08-11T13:28:37+00:00","dateModified":"2026-08-24T09:15:32+00:00","description":"Wie Messe M\u00fcnchen mit Powell ein visuell starkes Intranet aufgebaut hat: mehr Aufrufe, klare Struktur und eine Designsprache, die \u00fcberzeugt.","breadcrumb":{"@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#primaryimage","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2026\/03\/Messe-.png","width":675,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/powell-software.com\/de\/resources\/erfolgsgeschichten\/messe-muenchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/powell-software.com\/de\/"},{"@type":"ListItem","position":2,"name":"Success stories","item":"https:\/\/powell-software.com\/de\/resources\/.\/erfolgsgeschichten\/"},{"@type":"ListItem","position":3,"name":"Messe M\u00fcnchen: Ein Intranet-Relaunch&hellip;"}]},{"@type":"WebSite","@id":"https:\/\/powell-software.com\/de\/#website","url":"https:\/\/powell-software.com\/de\/","name":"Powell","description":"Intelligent Digital Workplace Suite","publisher":{"@id":"https:\/\/powell-software.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/powell-software.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/powell-software.com\/de\/#organization","name":"Powell","url":"https:\/\/powell-software.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/powell-software.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","contentUrl":"https:\/\/powell-software.com\/wp-content\/uploads\/2025\/03\/favicon.webp","width":969,"height":969,"caption":"Powell"},"image":{"@id":"https:\/\/powell-software.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PowellSoftware","https:\/\/x.com\/powellsoftware","https:\/\/www.youtube.com\/channel\/UCBX2pfEUCxJQWCKOx9hvv8w","https:\/\/fr.linkedin.com\/company\/powell-software"]},{"@type":"Person","@id":"https:\/\/powell-software.com\/de\/#\/schema\/person\/13226a9d5264862c57f9255d78f3ff80","name":"Lydia Schierig","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6f218430625e818a4f1521cdf7b7b1a19108569d8d67aed949b457ee59e9bcb?s=96&d=mm&r=g","caption":"Lydia Schierig"},"description":"B2B-Marketing trifft auf kulturelle Finesse: Lydia beweist, dass starker Content kein Selbstzweck ist, sondern Vertrauen schafft. Mit Erfahrung in den Bereichen LegalTech, Hospitality und SaaS hat sie Markenpr\u00e4senzen dort aufgebaut, wo Glaubw\u00fcrdigkeit alles ist. Bei Powell vereint sie deutsche Pr\u00e4zision mit Pariser Flair, um Kampagnen zu entwickeln, die echte Menschen erreichen. Ihr Fokus? Die Br\u00fccke zwischen Sales und Marketing zu schlagen, weil die besten Ergebnisse durch Teamarbeit entstehen. Wenn sie nicht gerade Strategien entwirft, erkundet sie die Stra\u00dfen von Paris, immer auf der Mission, den absolut besten Kaffee der Stadt zu finden.","sameAs":["https:\/\/www.linkedin.com\/in\/lydia-schierig\/"]}]}},"_links":{"self":[{"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/posts\/160346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/comments?post=160346"}],"version-history":[{"count":13,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/posts\/160346\/revisions"}],"predecessor-version":[{"id":160947,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/posts\/160346\/revisions\/160947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/media\/156531"}],"wp:attachment":[{"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/media?parent=160346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/categories?post=160346"},{"taxonomy":"audiences","embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/audiences?post=160346"},{"taxonomy":"interests","embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/interests?post=160346"},{"taxonomy":"products","embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/products?post=160346"},{"taxonomy":"zones","embeddable":true,"href":"https:\/\/powell-software.com\/de\/wp-json\/wp\/v2\/zones?post=160346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}